{"id":653,"date":"2025-11-09T17:23:24","date_gmt":"2025-11-09T17:23:24","guid":{"rendered":"https:\/\/nathacajigas.com\/?page_id=653"},"modified":"2026-02-25T17:36:24","modified_gmt":"2026-02-25T17:36:24","slug":"murals","status":"publish","type":"page","link":"https:\/\/nathacajigas.com\/es\/murals\/","title":{"rendered":"MURALES"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"653\" class=\"elementor elementor-653\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e1beea1 e-flex e-con-boxed e-con e-parent\" data-id=\"4e1beea1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68fa2e00 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"68fa2e00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Portfolio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-38fbe067 e-con-full e-flex e-con e-parent\" data-id=\"38fbe067\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d8c9f02 elementor-widget elementor-widget-text-editor\" data-id=\"7d8c9f02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>ALL MY<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15b55fe2 elementor-widget elementor-widget-text-editor\" data-id=\"15b55fe2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Murals<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13460a9 e-flex e-con-boxed e-con e-child\" data-id=\"13460a9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-03e8dfa e-con-full e-transform e-flex e-con e-child\" data-id=\"03e8dfa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:90,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-309bb40 elementor-widget__width-inherit elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"309bb40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d038a4d e-flex e-con-boxed e-con e-parent\" data-id=\"d038a4d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2ce2c8e e-con-full e-flex e-con e-child\" data-id=\"2ce2c8e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-efd80ed e-con-full e-flex e-con e-child\" data-id=\"efd80ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed65b66 imagen1 elementor-widget elementor-widget-image\" data-id=\"ed65b66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM2ODciLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1909\" height=\"2386\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0558-1.jpg\" class=\"attachment-full size-full wp-image-4046\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0558-1.jpg 1909w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0558-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0558-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0558-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0558-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0558-1-1639x2048.jpg 1639w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0558-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0558-1-600x750.jpg 600w\" sizes=\"(max-width: 1909px) 100vw, 1909px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16e413b e-con-full e-flex e-con e-child\" data-id=\"16e413b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2262e2 imagen1 elementor-widget elementor-widget-image\" data-id=\"a2262e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM2OTgiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1952\" height=\"2440\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/MuralHome-1.jpg\" class=\"attachment-full size-full wp-image-4054\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/MuralHome-1.jpg 1952w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/MuralHome-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/MuralHome-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/MuralHome-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/MuralHome-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/MuralHome-1-1638x2048.jpg 1638w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/MuralHome-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/MuralHome-1-600x750.jpg 600w\" sizes=\"(max-width: 1952px) 100vw, 1952px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e508e2e e-con-full e-flex e-con e-child\" data-id=\"e508e2e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94145f7 imagen1 elementor-widget elementor-widget-image\" data-id=\"94145f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3MDciLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1205\" height=\"1506\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7149-2-1.jpg\" class=\"attachment-full size-full wp-image-4055\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7149-2-1.jpg 1205w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7149-2-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7149-2-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7149-2-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7149-2-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7149-2-1-600x750.jpg 600w\" sizes=\"(max-width: 1205px) 100vw, 1205px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99726f4 e-con-full e-flex e-con e-child\" data-id=\"99726f4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ec321e imagen1 elementor-widget elementor-widget-image\" data-id=\"9ec321e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3MjIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/697D7999-9C64-4E09-9444-854EFF87DB70-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4067\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/697D7999-9C64-4E09-9444-854EFF87DB70-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/697D7999-9C64-4E09-9444-854EFF87DB70-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/697D7999-9C64-4E09-9444-854EFF87DB70-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/697D7999-9C64-4E09-9444-854EFF87DB70-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/697D7999-9C64-4E09-9444-854EFF87DB70-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/697D7999-9C64-4E09-9444-854EFF87DB70-1-1639x2048.jpg 1639w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/697D7999-9C64-4E09-9444-854EFF87DB70-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/697D7999-9C64-4E09-9444-854EFF87DB70-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f6f850e e-con-full e-flex e-con e-child\" data-id=\"f6f850e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a16f087 imagen1 elementor-widget elementor-widget-image\" data-id=\"a16f087\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3MjUiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_4217-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4053\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_4217-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_4217-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_4217-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_4217-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_4217-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_4217-1-1639x2048.jpg 1639w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_4217-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_4217-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f05a227 e-con-full e-flex e-con e-child\" data-id=\"f05a227\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2430c4b imagen1 elementor-widget elementor-widget-image\" data-id=\"2430c4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3MjkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0904-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4062\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0904-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0904-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0904-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0904-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0904-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0904-1-1639x2048.jpg 1639w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0904-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0904-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-46a704f e-con-full e-flex e-con e-child\" data-id=\"46a704f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a356fe imagen1 elementor-widget elementor-widget-image\" data-id=\"3a356fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3MzMiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"2250\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/5686835C-B96F-415E-8593-E05A59535129-1.jpg\" class=\"attachment-full size-full wp-image-4050\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/5686835C-B96F-415E-8593-E05A59535129-1.jpg 1800w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/5686835C-B96F-415E-8593-E05A59535129-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/5686835C-B96F-415E-8593-E05A59535129-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/5686835C-B96F-415E-8593-E05A59535129-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/5686835C-B96F-415E-8593-E05A59535129-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/5686835C-B96F-415E-8593-E05A59535129-1-1638x2048.jpg 1638w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/5686835C-B96F-415E-8593-E05A59535129-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/5686835C-B96F-415E-8593-E05A59535129-1-600x750.jpg 600w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e76628 e-con-full e-flex e-con e-child\" data-id=\"4e76628\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e14a65 imagen1 elementor-widget elementor-widget-image\" data-id=\"2e14a65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3MzciLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5483-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4052\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5483-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5483-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5483-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5483-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5483-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5483-1-1639x2048.jpg 1639w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5483-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5483-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54eb774 e-con-full e-flex e-con e-child\" data-id=\"54eb774\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15366cd imagen1 elementor-widget elementor-widget-image\" data-id=\"15366cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3NDYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1606-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4059\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1606-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1606-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1606-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1606-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1606-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1606-1-1639x2048.jpg 1639w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1606-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1606-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8cc653c e-con-full e-flex e-con e-child\" data-id=\"8cc653c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25c169e imagen1 elementor-widget elementor-widget-image\" data-id=\"25c169e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3NDkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/29529E8D-75D1-438C-955F-5CCBAB47B6BC-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4057\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/29529E8D-75D1-438C-955F-5CCBAB47B6BC-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/29529E8D-75D1-438C-955F-5CCBAB47B6BC-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/29529E8D-75D1-438C-955F-5CCBAB47B6BC-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/29529E8D-75D1-438C-955F-5CCBAB47B6BC-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/29529E8D-75D1-438C-955F-5CCBAB47B6BC-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/29529E8D-75D1-438C-955F-5CCBAB47B6BC-1-1638x2048.jpg 1638w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/29529E8D-75D1-438C-955F-5CCBAB47B6BC-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/29529E8D-75D1-438C-955F-5CCBAB47B6BC-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f9e1be e-con-full e-flex e-con e-child\" data-id=\"4f9e1be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a072e1 imagen1 elementor-widget elementor-widget-image\" data-id=\"8a072e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3NTIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/Mural-Home-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4047\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/Mural-Home-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/Mural-Home-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/Mural-Home-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/Mural-Home-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/Mural-Home-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/Mural-Home-1-1638x2048.jpg 1638w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/Mural-Home-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/Mural-Home-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b89766 e-con-full e-flex e-con e-child\" data-id=\"8b89766\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cc44bf imagen1 elementor-widget elementor-widget-image\" data-id=\"2cc44bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3NTUiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2047\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0487-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4058\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0487-1-scaled.jpg 2047w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0487-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0487-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0487-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0487-1-1228x1536.jpg 1228w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0487-1-1638x2048.jpg 1638w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0487-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0487-1-600x750.jpg 600w\" sizes=\"(max-width: 2047px) 100vw, 2047px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7754263 e-con-full e-flex e-con e-child\" data-id=\"7754263\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0b8de7b imagen1 elementor-widget elementor-widget-image\" data-id=\"0b8de7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3NjkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0409-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4065\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0409-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0409-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0409-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0409-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0409-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0409-1-1639x2048.jpg 1639w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0409-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0409-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06dc758 e-con-full e-flex e-con e-child\" data-id=\"06dc758\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d7a5a8 imagen1 elementor-widget elementor-widget-image\" data-id=\"0d7a5a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3NzIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_3213-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4060\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_3213-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_3213-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_3213-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_3213-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_3213-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_3213-1-1638x2048.jpg 1638w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_3213-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_3213-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e01dfc4 e-con-full e-flex e-con e-child\" data-id=\"e01dfc4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0261314 imagen1 elementor-widget elementor-widget-image\" data-id=\"0261314\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3NzYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5477-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4056\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5477-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5477-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5477-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5477-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5477-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5477-1-1638x2048.jpg 1638w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5477-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5477-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74a6df3 e-con-full e-flex e-con e-child\" data-id=\"74a6df3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c10137e imagen1 elementor-widget elementor-widget-image\" data-id=\"c10137e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3NzkiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0546-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4064\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0546-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0546-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0546-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0546-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0546-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0546-1-1638x2048.jpg 1638w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0546-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0546-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a7b1879 e-con-full e-flex e-con e-child\" data-id=\"a7b1879\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-81607d2 imagen1 elementor-widget elementor-widget-image\" data-id=\"81607d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3ODMiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1096-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4048\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1096-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1096-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1096-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1096-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1096-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1096-1-1639x2048.jpg 1639w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1096-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1096-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7feaa2d e-con-full e-flex e-con e-child\" data-id=\"7feaa2d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82ef17d imagen1 elementor-widget elementor-widget-image\" data-id=\"82ef17d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3ODYiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1156-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4051\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1156-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1156-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1156-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1156-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1156-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1156-1-1638x2048.jpg 1638w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1156-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_1156-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e57aa0 e-con-full e-flex e-con e-child\" data-id=\"1e57aa0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d8b550 imagen1 elementor-widget elementor-widget-image\" data-id=\"4d8b550\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3ODgiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5745-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4049\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5745-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5745-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5745-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5745-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5745-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5745-1-1639x2048.jpg 1639w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5745-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_5745-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-528f658 e-con-full e-flex e-con e-child\" data-id=\"528f658\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0acbb9 imagen1 elementor-widget elementor-widget-image\" data-id=\"e0acbb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM3OTciLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_9439-1-scaled.jpg\" class=\"attachment-full size-full wp-image-4066\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_9439-1-scaled.jpg 2048w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_9439-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_9439-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_9439-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_9439-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_9439-1-1638x2048.jpg 1638w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_9439-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_9439-1-600x750.jpg 600w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67ab3c9 e-con-full e-flex e-con e-child\" data-id=\"67ab3c9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-462fd66 imagen1 elementor-widget elementor-widget-image\" data-id=\"462fd66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjM4MDAiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2029\" height=\"2536\" src=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7388-1.jpg\" class=\"attachment-full size-full wp-image-4063\" alt=\"\" srcset=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7388-1.jpg 2029w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7388-1-240x300.jpg 240w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7388-1-819x1024.jpg 819w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7388-1-768x960.jpg 768w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7388-1-1229x1536.jpg 1229w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7388-1-1639x2048.jpg 1639w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7388-1-10x12.jpg 10w, https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_7388-1-600x750.jpg 600w\" sizes=\"(max-width: 2029px) 100vw, 2029px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Portfolio ALL MY Murals<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"folder":[],"class_list":["post-653","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MURALS -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nathacajigas.com\/es\/murals\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MURALS -\" \/>\n<meta property=\"og:description\" content=\"Portfolio ALL MY Murals\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nathacajigas.com\/es\/murals\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T17:36:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0558-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nathacajigas.com\\\/murals\\\/\",\"url\":\"https:\\\/\\\/nathacajigas.com\\\/murals\\\/\",\"name\":\"MURALS -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nathacajigas.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nathacajigas.com\\\/murals\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nathacajigas.com\\\/murals\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nathacajigas.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/IMG_0558-1.jpg\",\"datePublished\":\"2025-11-09T17:23:24+00:00\",\"dateModified\":\"2026-02-25T17:36:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nathacajigas.com\\\/murals\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nathacajigas.com\\\/murals\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/nathacajigas.com\\\/murals\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nathacajigas.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/IMG_0558-1.jpg\",\"contentUrl\":\"https:\\\/\\\/nathacajigas.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/IMG_0558-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nathacajigas.com\\\/murals\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/nathacajigas.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MURALS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nathacajigas.com\\\/#website\",\"url\":\"https:\\\/\\\/nathacajigas.com\\\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nathacajigas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MURALS -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nathacajigas.com\/es\/murals\/","og_locale":"es_ES","og_type":"article","og_title":"MURALS -","og_description":"Portfolio ALL MY Murals","og_url":"https:\/\/nathacajigas.com\/es\/murals\/","article_modified_time":"2026-02-25T17:36:24+00:00","og_image":[{"url":"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0558-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nathacajigas.com\/murals\/","url":"https:\/\/nathacajigas.com\/murals\/","name":"MURALS -","isPartOf":{"@id":"https:\/\/nathacajigas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nathacajigas.com\/murals\/#primaryimage"},"image":{"@id":"https:\/\/nathacajigas.com\/murals\/#primaryimage"},"thumbnailUrl":"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0558-1.jpg","datePublished":"2025-11-09T17:23:24+00:00","dateModified":"2026-02-25T17:36:24+00:00","breadcrumb":{"@id":"https:\/\/nathacajigas.com\/murals\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nathacajigas.com\/murals\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/nathacajigas.com\/murals\/#primaryimage","url":"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0558-1.jpg","contentUrl":"https:\/\/nathacajigas.com\/wp-content\/uploads\/2026\/02\/IMG_0558-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/nathacajigas.com\/murals\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/nathacajigas.com\/"},{"@type":"ListItem","position":2,"name":"MURALS"}]},{"@type":"WebSite","@id":"https:\/\/nathacajigas.com\/#website","url":"https:\/\/nathacajigas.com\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nathacajigas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"}]}},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/nathacajigas.com\/es\/wp-json\/wp\/v2\/pages\/653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nathacajigas.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nathacajigas.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nathacajigas.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nathacajigas.com\/es\/wp-json\/wp\/v2\/comments?post=653"}],"version-history":[{"count":338,"href":"https:\/\/nathacajigas.com\/es\/wp-json\/wp\/v2\/pages\/653\/revisions"}],"predecessor-version":[{"id":4696,"href":"https:\/\/nathacajigas.com\/es\/wp-json\/wp\/v2\/pages\/653\/revisions\/4696"}],"wp:attachment":[{"href":"https:\/\/nathacajigas.com\/es\/wp-json\/wp\/v2\/media?parent=653"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/nathacajigas.com\/es\/wp-json\/wp\/v2\/folder?post=653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}